{"id":6545,"date":"2019-09-21T14:29:28","date_gmt":"2019-09-21T12:29:28","guid":{"rendered":"https:\/\/discoverportovenere.com\/?p=6545"},"modified":"2023-05-17T14:47:05","modified_gmt":"2023-05-17T12:47:05","slug":"scalo-crociera-la-spezia","status":"publish","type":"post","link":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/","title":{"rendered":"Scalo Crociera a La Spezia: cosa fare in un giorno?"},"content":{"rendered":"\n<p>Se stai pensando di goderti una crociera, e <a href=\"https:\/\/discoverportovenere.com\/it\/cosa-vedere-la-spezia\/\">La Spezia<\/a> figura come porto di scalo, allora devi sfruttare al meglio il tempo a disposizione in questa splendida parte della riviera ligure. Cosa c&#8217;\u00e8 da fare in un giorno a La Spezia, <a href=\"https:\/\/discoverportovenere.com\/it\/guida-viaggio-definitiva-portovenere\/\">Portovenere<\/a> o nelle sue vicinanze? Molti di coloro che scelgono di godersi una crociera sanno di poter visitare le famose Cinque Terre da La Spezia, ma ci sono anche altre alternative incredibili tra il <a href=\"https:\/\/discoverportovenere.com\/it\/golfo-dei-poeti\/\">Golfo dei Poeti in Liguria<\/a> e la Toscana settentrionale.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Esplorare Portovenere e il Golfo dei Poeti<\/h2>\n\n\n\n<p>Il Golfo di La Spezia \u00e8 noto anche come Golfo dei Poeti, per via dei tantissimi artisti che lo hanno visitato nel corso della storia, scegliendolo spesso come seconda casa o luogo di ispirazione. Si estende dal borgo di <a href=\"https:\/\/discoverportovenere.com\/it\/cose-da-fare-a-portovenere\/\">Portovenere<\/a> a ovest, attraverso La Spezia e fino ai paesi di <a href=\"https:\/\/discoverportovenere.com\/it\/lerici-viaggio-borgo-dei-poeti\/\">Lerici<\/a> e <a href=\"https:\/\/discoverportovenere.com\/it\/tellaro-fiascherino-san-terenzo\/\">Tellaro<\/a> nella parte orientale della riviera ligure, al confine con la Toscana.<\/p>\n\n\n\n<p>Negli ultimi anni, sempre pi\u00f9 giornalisti che si occupano di viaggi, blogger e turisti hanno elogiato Portovenere per la sua bellezza, la natura, la storia e l&#8217;autenticit\u00e0, consigliandolo come alternativa alle Cinque Terre. \u00c8 il borgo da visitare se si apprezza il concetto di Slow Travel fuori dai sentieri battuti.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"363\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/portovenere-cruise-stop-la-spezia.jpg\" alt=\"portovenere-cruise-stop-la-spezia\" class=\"wp-image-3614\"\/><figcaption class=\"wp-element-caption\"><em>Portovenere<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Da La Spezia, si pu\u00f2 raggiungere Portovenere con 20 minuti di macchina se si noleggia un&#8217;auto, in taxi o in autobus. L&#8217;alternativa pi\u00f9 panoramica \u00e8 la barca: si pu\u00f2 raggiungere Portovenere da La Spezia con il battello, che impiega circa 45 minuti. Oppure si pu\u00f2 optare per un transfer veloce in barca, ad esempio con HopHop Boat.<\/p>\n\n\n\n<p>Visitare il Golfo dei Poeti \u00e8 una delle esperienze pi\u00f9 gratificanti e sorprendenti da vivere durante la sosta a La Spezia. Esistono tour esclusivi che permettono di visitare Portovenere ed esplorare la baia dal mare, aggiungendo un tocco di storia, cultura e gastronomia. Il <a href=\"https:\/\/discoverportovenere.com\/it\/tour-ostriche-portovenere\/\">Tour Delle Ostriche<\/a> ne \u00e8 un esempio: concede il tempo sufficiente per visitare lentamente la suggestiva baia e per tornare alla nave da crociera a La Spezia entro le 17.00.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"970\" height=\"546\" src=\"https:\/\/www.youtube.com\/embed\/2dqX-41hQ50?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=it-IT&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<p>Se si preferisce trascorrere pi\u00f9 tempo a Portovenere, si possono <a href=\"https:\/\/discoverportovenere.com\/it\/degustazione-vini-porto-venere\/\">degustare vini<\/a> o seguire lezioni di cucina, fare escursioni sull&#8217;<a href=\"https:\/\/discoverportovenere.com\/it\/natura-escursioni-isola-palmaria\/\">Isola Palmaria<\/a>, shopping lungo il carugio principale. Per ulteriori idee, dai un&#8217;occhiata alle <a href=\"https:\/\/discoverportovenere.com\/it\/cose-da-fare-a-portovenere\/\">10 cose da fare a Portovenere<\/a>. Se ti viene fame e vuoi fermarti per un pranzo veloce ma delizioso con vista panoramica, o vuoi gustare un cocktail speciale, recati al <a href=\"http:\/\/palmariarestaurant.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ristorante Palmaria e al Venus Bar<\/a> proprio di fronte al porto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cose da fare a La Spezia<\/h2>\n\n\n\n<p>Preferisci oziare o ti senti ispirato dal panorama? Soggiorna a La Spezia! Potrai passeggiare per la citt\u00e0 al ritmo che preferisci e senza fretta. La citt\u00e0 vanta un incantevole lungomare che si affaccia sull&#8217;ampia baia, alternando edifici storici a giardini, palme e al moderno ponte bianco chiamato Ponte Thaon di Revel, che collega il Porto Mirabello con il Lungomare Morin. Nel centro storico troverai negozi e ristoranti, mentre se adori l&#8217;arte e la storia non puoi non fare un salto al Museo Tecnico Navale, al Castello di San Giorgio e al CAMeC &#8211; Centro Arte Moderna e Contemporanea. <a href=\"https:\/\/discoverportovenere.com\/it\/cosa-vedere-la-spezia\/\">Maggiori informazioni su cosa fare a La Spezia<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port.jpg\" alt=\"la-spezia-cruise-port guide\" class=\"wp-image-3612\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port.jpg 640w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port-150x150.jpg 150w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\"><em>Giardini e palme sul lungomare di La Spezia<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">I borghi pi\u00f9 famosi: visitare le Cinque Terre da La Spezia<\/h2>\n\n\n\n<p>Se hai dalle quattro alle otto ore di tempo libero durante la sosta a La Spezia, puoi raggiungere le <a href=\"https:\/\/discoverportovenere.com\/it\/portovenere-cinque-terre-cosa-fare\/\">Cinque Terre<\/a> in barca o in treno.<\/p>\n\n\n\n<p>Puoi ammirare la costa dal mare con i traghetti che partono da La Spezia e da Portovenere e, a seconda dell&#8217;ora in cui prendi il battello, dovresti avere abbastanza tempo a disposizione per scendere e visitare a piedi almeno due dei cinque borghi.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"437\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/cinque-terre-cruise-stop-la-spezia.jpg\" alt=\"cinque-terre-cruise-stop-la-spezia\" class=\"wp-image-3615\"\/><figcaption class=\"wp-element-caption\"><em>Vernazza, una delle Cinque Terre<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>I treni sono la soluzione pi\u00f9 veloce, poich\u00e9 partono regolarmente dalla stazione ferroviaria di La Spezia e collegano i paesi con brevi tratte da tre a sette minuti. Perci\u00f2, \u00e8 possibile visitare pi\u00f9 borghi, tra cui la caratteristica Corniglia, che non pu\u00f2 essere raggiunta in barca.<\/p>\n\n\n\n<p>Ricorda che le Cinque Terre sono diventate una <a href=\"https:\/\/discoverportovenere.com\/it\/portovenere-o-cinque-terre\/\">destinazione turistica popolare<\/a> negli ultimi anni, con conseguenti preoccupazioni per il turismo di massa nel parco naturale protetto che circonda i paesi di Riomaggiore, Manarola, Corniglia, Vernazza e Monterosso. Potresti trovare tanta gente e code, soprattutto tra luglio e settembre.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Visitare la Toscana da La Spezia: Pisa, Lucca, le Cave di Marmo di Carrara e Firenze<\/h4>\n\n\n\n<p>I treni consentono di visitare Pisa o <a href=\"https:\/\/discoverportovenere.com\/it\/museo-zecca-lucca\/\">Lucca<\/a> da La Spezia in modo facile e veloce, con una gita di mezza giornata. Un&#8217;altra alternativa interessante per scoprire la citt\u00e0, l&#8217;arte e la storia \u00e8 una visita guidata alle <a href=\"https:\/\/discoverportovenere.com\/it\/tour-cave-marmo-portovenere-carrara\/\">cave di marmo di Carrara<\/a>, utilizzate da Michelangelo per alcune delle sue opere pi\u00f9 iconiche. Carrara si trova a soli 40 minuti di auto da La Spezia e ci sono tour che comprendono il transfer, la visita alla cava di marmo e anche un delizioso pranzo in loco.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"489\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/08\/carrara-marble-tour-quarry-tuscany.jpg\" alt=\"carrara marble tour quarry tuscany\" class=\"wp-image-2922\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/08\/carrara-marble-tour-quarry-tuscany.jpg 800w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/08\/carrara-marble-tour-quarry-tuscany-350x214.jpg 350w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/08\/carrara-marble-tour-quarry-tuscany-768x469.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\"><em>Cava di marmo a Carrara<\/em><\/figcaption><\/figure>\n\n\n\n<p>Molte persone che viaggiano in crociera vogliono visitare Firenze da La Spezia: anche se fare un giro molto veloce della citt\u00e0 possa non dispiacerti, ricorda che passerai met\u00e0 del tempo in treno o in auto, a seconda del tipo di transfer scelto.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Combinare le destinazioni durante lo scalo crociera a La Spezia?<\/h4>\n\n\n\n<p>Se ti stai chiedendo se sia possibile visitare le Cinque Terre e Pisa o qualsiasi altra citt\u00e0 della Toscana in un solo giorno, la risposta \u00e8 no. Dovresti mettere in conto troppi transfer e troppe cose da vedere in poco tempo. Lo stesso vale per quanto riguarda il <a href=\"https:\/\/discoverportovenere.com\/it\/9-poeti-che-amarono-il-golfo-dei-poeti\/\">Golfo dei Poeti<\/a> e le Cinque Terre: si pu\u00f2 fare se organizzi alla perfezione i tuoi spostamenti indipendenti, oppure se scegli un tour o noleggi un motoscafo privato, ma fidati se ti diciamo che queste destinazioni meritano di essere ammirate, apprezzate e riassaporate con calma. La soluzione migliore \u00e8 quella di scegliere una destinazione durante la tua crociera a La Spezia e di prenderti il tempo necessario per scoprire l&#8217;essenza della storia, della cucina e della cultura locale.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Main cover photo credit: ADSP DEL MAR LIGURE ORIENTALE ar.adspmarligureorientale.it<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se stai pensando di goderti una crociera, e La Spezia figura come porto di scalo, allora devi sfruttare al meglio il tempo a disposizione in&hellip;<\/p>\n","protected":false},"author":2,"featured_media":5669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[173],"tags":[219,223,226,247,257,286,315],"class_list":["post-6545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-idee-di-viaggio","tag-carrara-it","tag-cinque-terre-it","tag-crociera","tag-golfo-dei-poeti","tag-la-spezia-it","tag-portovenere","tag-toscana","post-grid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scalo Crociera a La Spezia: Cosa Fare E Vedere In Un Giorno?<\/title>\n<meta name=\"description\" content=\"Consigli su fare e vedere durante lo scalo se arrivi al Porto di La Spezia durante una crociera| Visita Portovenere, Cinque Terre, Lerici...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scalo Crociera a La Spezia: Cosa Fare E Vedere In Un Giorno?\" \/>\n<meta property=\"og:description\" content=\"Consigli su fare e vedere durante lo scalo se arrivi al Porto di La Spezia durante una crociera| Visita Portovenere, Cinque Terre, Lerici...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/\" \/>\n<meta property=\"og:site_name\" content=\"Discover Portovenere Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grandhotelportovenere\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-21T12:29:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-17T12:47:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port-stop.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"557\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portovenere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ghportovenere\" \/>\n<meta name=\"twitter:site\" content=\"@ghportovenere\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portovenere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/\"},\"author\":{\"name\":\"Portovenere\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/person\\\/77b4e306e5541ddeea527c99f7a03e89\"},\"headline\":\"Scalo Crociera a La Spezia: cosa fare in un giorno?\",\"datePublished\":\"2019-09-21T12:29:28+00:00\",\"dateModified\":\"2023-05-17T12:47:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/\"},\"wordCount\":1018,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/la-spezia-cruise-port-stop.jpg\",\"keywords\":[\"carrara\",\"cinque terre\",\"crociera\",\"golfo dei poeti\",\"la spezia\",\"portovenere\",\"toscana\"],\"articleSection\":[\"Idee di viaggio\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/\",\"name\":\"Scalo Crociera a La Spezia: Cosa Fare E Vedere In Un Giorno?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/la-spezia-cruise-port-stop.jpg\",\"datePublished\":\"2019-09-21T12:29:28+00:00\",\"dateModified\":\"2023-05-17T12:47:05+00:00\",\"description\":\"Consigli su fare e vedere durante lo scalo se arrivi al Porto di La Spezia durante una crociera| Visita Portovenere, Cinque Terre, Lerici...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/la-spezia-cruise-port-stop.jpg\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/la-spezia-cruise-port-stop.jpg\",\"width\":1200,\"height\":557},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/scalo-crociera-la-spezia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scalo Crociera a La Spezia: cosa fare in un giorno?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\",\"name\":\"Discover Portovenere Blog\",\"description\":\"between Liguria & Tuscany\",\"publisher\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\",\"name\":\"Discover Portovenere - Grand Hotel Portovenere\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/discover-portovenere-liguria-tuscany-700.png\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/discover-portovenere-liguria-tuscany-700.png\",\"width\":700,\"height\":92,\"caption\":\"Discover Portovenere - Grand Hotel Portovenere\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grandhotelportovenere\",\"https:\\\/\\\/x.com\\\/ghportovenere\",\"https:\\\/\\\/www.instagram.com\\\/ghportovenere\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/grand-hotel-portovenere\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Portoveneregrand\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/person\\\/77b4e306e5541ddeea527c99f7a03e89\",\"name\":\"Portovenere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"caption\":\"Portovenere\"},\"description\":\"5-star hotel in Portovenere, between the Bay of Poets and Cinque Terre in Liguria. Explore this beautiful Italian destination with Discover Portovenere Blog.\",\"sameAs\":[\"https:\\\/\\\/www.portoveneregrand.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Grand-Hotel-Portovenere\\\/158392434188761\",\"https:\\\/\\\/www.instagram.com\\\/ghportovenere\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ghportovenere\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scalo Crociera a La Spezia: Cosa Fare E Vedere In Un Giorno?","description":"Consigli su fare e vedere durante lo scalo se arrivi al Porto di La Spezia durante una crociera| Visita Portovenere, Cinque Terre, Lerici...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/","og_locale":"it_IT","og_type":"article","og_title":"Scalo Crociera a La Spezia: Cosa Fare E Vedere In Un Giorno?","og_description":"Consigli su fare e vedere durante lo scalo se arrivi al Porto di La Spezia durante una crociera| Visita Portovenere, Cinque Terre, Lerici...","og_url":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/","og_site_name":"Discover Portovenere Blog","article_publisher":"https:\/\/www.facebook.com\/grandhotelportovenere","article_author":"https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761","article_published_time":"2019-09-21T12:29:28+00:00","article_modified_time":"2023-05-17T12:47:05+00:00","og_image":[{"width":1200,"height":557,"url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port-stop.jpg","type":"image\/jpeg"}],"author":"Portovenere","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ghportovenere","twitter_site":"@ghportovenere","twitter_misc":{"Scritto da":"Portovenere","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/#article","isPartOf":{"@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/"},"author":{"name":"Portovenere","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/person\/77b4e306e5541ddeea527c99f7a03e89"},"headline":"Scalo Crociera a La Spezia: cosa fare in un giorno?","datePublished":"2019-09-21T12:29:28+00:00","dateModified":"2023-05-17T12:47:05+00:00","mainEntityOfPage":{"@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/"},"wordCount":1018,"commentCount":0,"publisher":{"@id":"https:\/\/discoverportovenere.com\/it\/#organization"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/#primaryimage"},"thumbnailUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port-stop.jpg","keywords":["carrara","cinque terre","crociera","golfo dei poeti","la spezia","portovenere","toscana"],"articleSection":["Idee di viaggio"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/","url":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/","name":"Scalo Crociera a La Spezia: Cosa Fare E Vedere In Un Giorno?","isPartOf":{"@id":"https:\/\/discoverportovenere.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/#primaryimage"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/#primaryimage"},"thumbnailUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port-stop.jpg","datePublished":"2019-09-21T12:29:28+00:00","dateModified":"2023-05-17T12:47:05+00:00","description":"Consigli su fare e vedere durante lo scalo se arrivi al Porto di La Spezia durante una crociera| Visita Portovenere, Cinque Terre, Lerici...","breadcrumb":{"@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/#primaryimage","url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port-stop.jpg","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port-stop.jpg","width":1200,"height":557},{"@type":"BreadcrumbList","@id":"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/discoverportovenere.com\/it\/"},{"@type":"ListItem","position":2,"name":"Scalo Crociera a La Spezia: cosa fare in un giorno?"}]},{"@type":"WebSite","@id":"https:\/\/discoverportovenere.com\/it\/#website","url":"https:\/\/discoverportovenere.com\/it\/","name":"Discover Portovenere Blog","description":"between Liguria & Tuscany","publisher":{"@id":"https:\/\/discoverportovenere.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/discoverportovenere.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/discoverportovenere.com\/it\/#organization","name":"Discover Portovenere - Grand Hotel Portovenere","url":"https:\/\/discoverportovenere.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/discover-portovenere-liguria-tuscany-700.png","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/discover-portovenere-liguria-tuscany-700.png","width":700,"height":92,"caption":"Discover Portovenere - Grand Hotel Portovenere"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grandhotelportovenere","https:\/\/x.com\/ghportovenere","https:\/\/www.instagram.com\/ghportovenere\/","https:\/\/www.linkedin.com\/company\/grand-hotel-portovenere","https:\/\/www.youtube.com\/c\/Portoveneregrand"]},{"@type":"Person","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/person\/77b4e306e5541ddeea527c99f7a03e89","name":"Portovenere","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","url":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","caption":"Portovenere"},"description":"5-star hotel in Portovenere, between the Bay of Poets and Cinque Terre in Liguria. Explore this beautiful Italian destination with Discover Portovenere Blog.","sameAs":["https:\/\/www.portoveneregrand.com\/","https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761","https:\/\/www.instagram.com\/ghportovenere\/","https:\/\/x.com\/https:\/\/twitter.com\/ghportovenere"]}]}},"jetpack_featured_media_url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2019\/09\/la-spezia-cruise-port-stop.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5GNh5-1Hz","jetpack-related-posts":[{"id":6642,"url":"https:\/\/discoverportovenere.com\/it\/cosa-vedere-la-spezia\/","url_meta":{"origin":6545,"position":0},"title":"Cosa Vedere a La Spezia","author":"Portovenere","date":"28 Agosto 2015","format":false,"excerpt":"La Spezia, che \u00e8 uno dei principali porti militari e commerciali italiani, offre varie interessanti attrazioni e cose da fare. Spezia \u00e8 la citt\u00e0 pi\u00f9 grande del Golfo dei Poeti e capoluogo dell'omonima provincia ligure. La citt\u00e0 ospita numerosi musei. Uno dei pi\u00f9 caratteristici \u00e8 il Museo Tecnico Navale. Situato\u2026","rel":"","context":"In &quot;Barche&quot;","block_context":{"text":"Barche","link":"https:\/\/discoverportovenere.com\/it\/categoria\/barche\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/08\/La-Spezia-Marine-Festival.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/08\/La-Spezia-Marine-Festival.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/08\/La-Spezia-Marine-Festival.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/08\/La-Spezia-Marine-Festival.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/08\/La-Spezia-Marine-Festival.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/08\/La-Spezia-Marine-Festival.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":6554,"url":"https:\/\/discoverportovenere.com\/it\/primavera-golfo-dei-poeti\/","url_meta":{"origin":6545,"position":1},"title":"Primavera nel Golfo dei Poeti: cosa fare?","author":"Portovenere","date":"18 Febbraio 2023","format":false,"excerpt":"Stai riflettendo su dove andare per le tue prossime vacanze di primavera? Tra le sue innumerevoli attrazioni, la Liguria custodisce una destinazione da non perdere vicinissima alle Cinque Terre e alla Toscana. Il nome stesso di questa destinazione, Golfo dei Poeti, ti incuriosir\u00e0\u2026 Questo splendido golfo si estende tra i\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5936,"url":"https:\/\/discoverportovenere.com\/it\/spiagge-piu-belle-golfo-dei-poeti-spezia\/","url_meta":{"origin":6545,"position":2},"title":"Le spiagge pi\u00f9 belle del Golfo dei Poeti","author":"Portovenere","date":"14 Giugno 2022","format":false,"excerpt":"Nel Golfo dei Poeti si trovano le spiagge pi\u00f9 belle della provincia della Spezia. Questo tratto di costa tra le Cinque Terre in Liguria e la Versilia in Toscana alterna baie ciottolose, scogliere e spiagge sabbiose. Ci sono diverse spiagge affascinanti, alcune famose e facili da raggiungere, altre poco conosciute\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/La-Spezia-Best-Beaches-Maurizio-Pessione.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/La-Spezia-Best-Beaches-Maurizio-Pessione.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/La-Spezia-Best-Beaches-Maurizio-Pessione.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/La-Spezia-Best-Beaches-Maurizio-Pessione.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/La-Spezia-Best-Beaches-Maurizio-Pessione.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6804,"url":"https:\/\/discoverportovenere.com\/it\/guida-viaggio-definitiva-portovenere\/","url_meta":{"origin":6545,"position":3},"title":"Portovenere: tutto quello che c&#8217;\u00e8 da sapere","author":"Portovenere","date":"3 Ottobre 2021","format":false,"excerpt":"Tra le mete pi\u00f9 famose della Riviera Di Levante ci sono le Cinque Terre, splendidi borghi marinari che meritano di essere esplorati con calma. Tuttavia, in questa parte della Liguria c'\u00e8 una sesta localit\u00e0 segreta: Portovenere \u00e8 la destinazione ideale per i viaggiatori che preferiscono uscire dai sentieri battuti. Questa\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/10\/travel-guide-portovenere-italy.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/10\/travel-guide-portovenere-italy.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/10\/travel-guide-portovenere-italy.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/10\/travel-guide-portovenere-italy.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/10\/travel-guide-portovenere-italy.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/10\/travel-guide-portovenere-italy.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":6333,"url":"https:\/\/discoverportovenere.com\/it\/autunno-nel-golfo-dei-poeti-idee-viaggio\/","url_meta":{"origin":6545,"position":4},"title":"Autunno nel Golfo dei Poeti","author":"Portovenere","date":"1 Ottobre 2024","format":false,"excerpt":"Dove andare in vacanza in autunno in Italia? Dopo tutto, questa variopinta stagione \u00e8 proprio dietro l'angolo! Se stai cercando una destinazione suggestiva, ricca di carattere e di attivit\u00e0 interessanti, potresti approfittare dell'autunno nel Golfo dei Poeti (o Golfo di La Spezia) in Liguria. I meravigliosi panorami di questa zona\u2026","rel":"","context":"In &quot;Enogastronomia&quot;","block_context":{"text":"Enogastronomia","link":"https:\/\/discoverportovenere.com\/it\/categoria\/enogastronomia\/"},"img":{"alt_text":"autumn in the bay of poets portovenere fall break by Argyrios Gerentes genovagerry on Flickr.","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/09\/autumn-in-the-bay-of-poets-portovenere-fall-break-by-Argyrios-Gerentes-genovagerry-on-Flickr-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/09\/autumn-in-the-bay-of-poets-portovenere-fall-break-by-Argyrios-Gerentes-genovagerry-on-Flickr-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/09\/autumn-in-the-bay-of-poets-portovenere-fall-break-by-Argyrios-Gerentes-genovagerry-on-Flickr-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/09\/autumn-in-the-bay-of-poets-portovenere-fall-break-by-Argyrios-Gerentes-genovagerry-on-Flickr-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/09\/autumn-in-the-bay-of-poets-portovenere-fall-break-by-Argyrios-Gerentes-genovagerry-on-Flickr-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5944,"url":"https:\/\/discoverportovenere.com\/it\/come-arrivare-muoversi-nel-golfo-dei-poeti\/","url_meta":{"origin":6545,"position":5},"title":"Come arrivare a Portovenere e muoversi nel Golfo dei Poeti","author":"Portovenere","date":"11 Febbraio 2026","format":false,"excerpt":"Portovenere \u00e8 un meraviglioso sito Patrimonio dell'Umanit\u00e0 UNESCO in Liguria, incastonato tra le aspre Cinque Terre e La Spezia, nell'idilliaco Golfo dei Poeti. Che tu ti stia chiedendo come arrivare a Portovenere o stia cercando il modo migliore per spostarti tra Lerici, La Spezia e le Cinque Terre, questa guida\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/02\/gulf-of-poets-transport-cinque-terre.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/02\/gulf-of-poets-transport-cinque-terre.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/02\/gulf-of-poets-transport-cinque-terre.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/02\/gulf-of-poets-transport-cinque-terre.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/02\/gulf-of-poets-transport-cinque-terre.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts\/6545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/comments?post=6545"}],"version-history":[{"count":0,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts\/6545\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/media\/5669"}],"wp:attachment":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/media?parent=6545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/categories?post=6545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/tags?post=6545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}