{"id":6563,"date":"2015-11-27T11:42:21","date_gmt":"2015-11-27T09:42:21","guid":{"rendered":"https:\/\/discoverportovenere.com\/?p=6563"},"modified":"2023-05-17T15:00:39","modified_gmt":"2023-05-17T13:00:39","slug":"poesia-eugenio-montale-portovenere","status":"publish","type":"post","link":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/","title":{"rendered":"L&#8217;ode di Eugenio Montale a Portovenere"},"content":{"rendered":"\n<p><a href=\"https:\/\/discoverportovenere.com\/it\/guida-viaggio-definitiva-portovenere\/\">Portovenere<\/a> e il Golfo di La Spezia hanno affascinato tantissimi scrittori nel corso del tempo, tanto che la zona \u00e8 conosciuta con il nome di <a href=\"https:\/\/discoverportovenere.com\/it\/golfo-dei-poeti\/\">Golfo dei Poeti<\/a>. Un artista in particolare ha catturato l&#8217;essenza del borgo in una poesia dedicata a Portovenere. Eugenio Montale (1896 &#8211; 1981) \u00e8 stato poeta, scrittore ed editore italiano. Ha vinto il Premio Nobel per la Letteratura nel 1975.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"alignright\"><img loading=\"lazy\" decoding=\"async\" width=\"208\" height=\"300\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/eugenio-montale.jpg\" alt=\"Eugenio Montale (1896 \u2013 1981) was an Italian poet, prose writer and editor.\" class=\"wp-image-702\"\/><\/figure>\n<\/div>\n\n\n<p><em>Nonostante Eugenio Montale abbia prodotto solo cinque volumi di poesie nei suoi primi cinquant&#8217;anni di attivit\u00e0, quando l&#8217;Accademia di Svezia assegn\u00f2 al poeta e critico italiano il Premio Nobel per la Letteratura del 1975 lo defin\u00ec &#8220;uno dei pi\u00f9 importanti poeti dell&#8217;Occidente contemporaneo&#8221;, secondo quanto riportato da Publishers Weekly.<\/em> [Poetry Foundation <a href=\"http:\/\/www.poetryfoundation.org\/bio\/eugenio-montale\" target=\"_blank\" rel=\"noopener\">poetryfoundation.org<\/a>]<\/p>\n<\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">Portovenere (1925), Eugenio Montale<\/h4>\n\n\n\n<p><em>L\u00e0 fuoresce il tritone<\/em><br><em>dai flutti che lambiscono<\/em><br><em>le soglie d\u2019un cristiano<\/em><br><em>tempio, ed ogni ora prossima<\/em><br><em>\u00e8 antica. Ogni dubbiezza<\/em><br><em>si conduce per mano<\/em><br><em>come una fanciulletta amica.<\/em><\/p>\n\n\n\n<p><em>L\u00e0 non \u00e8 chi si guardi<\/em><br><em>o stia di s\u00e9 in ascolto.<\/em><br><em>Quivi sei alle origini<\/em><br><em>e decidere \u00e8 stolto:<\/em><br><em>ripartirai pi\u00f9 tardi per assumere un volto.<\/em><\/p>\n\n\n\n<p>Il tempio cristiano citato nella poesia \u00e8 la Chiesa di San Pietro, un edificio in stile gotico che si erge sublime sulla scogliera a picco sul mare proprio sopra la Grotta di Byron di Portovenere.<\/p>\n\n\n\n<p>La poesia di Montale rende l&#8217;idea delle sensazioni che un visitatore meditativo prova arrivando a Portovenere, sospeso tra natura, storia, mito e beata bellezza!<\/p>\n\n\n<div class=\"wp-block-image wp-image-712 size-full\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"290\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-Lord-Byron-Grotto.jpg\" alt=\"Lord Byron's Grotto in Portovenere, Liguria Bay of Poets\" class=\"wp-image-712\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-Lord-Byron-Grotto.jpg 645w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-Lord-Byron-Grotto-350x157.jpg 350w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><figcaption class=\"wp-element-caption\">Lord Byron fu un altro poeta che si innamor\u00f2 di Portovenere. Si dice che meditasse in una grotta situata sotto la Chiesa di San Pietro. &#8220;Grotta Arpaia&#8221; \u00e8 oggi conosciuta anche come &#8220;Grotta Byron&#8221;. L&#8217;insegna che d\u00e0 il benvenuto in questo luogo magico recita: &#8220;<em>Questa grotta ispiratrice di Lord Byron ricorda l\u2019immortale poeta che ardito nuotatore sfid\u00f2 le onde del mare da Portovenere a Lerici<\/em>&#8220;.<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Scopri di pi\u00f9 sulla <a href=\"https:\/\/discoverportovenere.com\/it\/storia-di-portovenere\/\">storia di Portovenere<\/a> e <a href=\"https:\/\/discoverportovenere.com\/it\/9-poeti-che-amarono-il-golfo-dei-poeti\/\">9 poeti che amarono il Golfo Dei Poet<\/a>i.<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Portovenere e il Golfo di La Spezia hanno affascinato tantissimi scrittori nel corso del tempo, tanto che la zona \u00e8 conosciuta con il nome di&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4992,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[193],"tags":[234,284,286],"class_list":["post-6563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-poesia","tag-eugenio-montale-it","tag-poesia","tag-portovenere","post-grid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Portovenere Nella Poesia: L&#039;Ode Di Eugenio Montale<\/title>\n<meta name=\"description\" content=\"La poesia di Eugenio Montale rende l&#039;idea delle sensazioni che proverai arrivando nel borgo sospeso tra natura, storia, mito e bellezza!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portovenere Nella Poesia: L&#039;Ode Di Eugenio Montale\" \/>\n<meta property=\"og:description\" content=\"La poesia di Eugenio Montale rende l&#039;idea delle sensazioni che proverai arrivando nel borgo sospeso tra natura, storia, mito e bellezza!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/\" \/>\n<meta property=\"og:site_name\" content=\"Discover Portovenere Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grandhotelportovenere\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-27T09:42:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-17T13:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portovenere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ghportovenere\" \/>\n<meta name=\"twitter:site\" content=\"@ghportovenere\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portovenere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/\"},\"author\":{\"name\":\"Portovenere\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/person\\\/77b4e306e5541ddeea527c99f7a03e89\"},\"headline\":\"L&#8217;ode di Eugenio Montale a Portovenere\",\"datePublished\":\"2015-11-27T09:42:21+00:00\",\"dateModified\":\"2023-05-17T13:00:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/\"},\"wordCount\":320,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Portovenere-Poem-by-Eugenio-Montale.jpg\",\"keywords\":[\"eugenio montale\",\"poesia\",\"portovenere\"],\"articleSection\":[\"Poesia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/\",\"name\":\"Portovenere Nella Poesia: L'Ode Di Eugenio Montale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Portovenere-Poem-by-Eugenio-Montale.jpg\",\"datePublished\":\"2015-11-27T09:42:21+00:00\",\"dateModified\":\"2023-05-17T13:00:39+00:00\",\"description\":\"La poesia di Eugenio Montale rende l'idea delle sensazioni che proverai arrivando nel borgo sospeso tra natura, storia, mito e bellezza!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Portovenere-Poem-by-Eugenio-Montale.jpg\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/Portovenere-Poem-by-Eugenio-Montale.jpg\",\"width\":750,\"height\":441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/poesia-eugenio-montale-portovenere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;ode di Eugenio Montale a Portovenere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\",\"name\":\"Discover Portovenere Blog\",\"description\":\"between Liguria & Tuscany\",\"publisher\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\",\"name\":\"Discover Portovenere - Grand Hotel Portovenere\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/discover-portovenere-liguria-tuscany-700.png\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/discover-portovenere-liguria-tuscany-700.png\",\"width\":700,\"height\":92,\"caption\":\"Discover Portovenere - Grand Hotel Portovenere\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grandhotelportovenere\",\"https:\\\/\\\/x.com\\\/ghportovenere\",\"https:\\\/\\\/www.instagram.com\\\/ghportovenere\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/grand-hotel-portovenere\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Portoveneregrand\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/person\\\/77b4e306e5541ddeea527c99f7a03e89\",\"name\":\"Portovenere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"caption\":\"Portovenere\"},\"description\":\"5-star hotel in Portovenere, between the Bay of Poets and Cinque Terre in Liguria. Explore this beautiful Italian destination with Discover Portovenere Blog.\",\"sameAs\":[\"https:\\\/\\\/www.portoveneregrand.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Grand-Hotel-Portovenere\\\/158392434188761\",\"https:\\\/\\\/www.instagram.com\\\/ghportovenere\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ghportovenere\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portovenere Nella Poesia: L'Ode Di Eugenio Montale","description":"La poesia di Eugenio Montale rende l'idea delle sensazioni che proverai arrivando nel borgo sospeso tra natura, storia, mito e bellezza!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/","og_locale":"it_IT","og_type":"article","og_title":"Portovenere Nella Poesia: L'Ode Di Eugenio Montale","og_description":"La poesia di Eugenio Montale rende l'idea delle sensazioni che proverai arrivando nel borgo sospeso tra natura, storia, mito e bellezza!","og_url":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/","og_site_name":"Discover Portovenere Blog","article_publisher":"https:\/\/www.facebook.com\/grandhotelportovenere","article_author":"https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761","article_published_time":"2015-11-27T09:42:21+00:00","article_modified_time":"2023-05-17T13:00:39+00:00","og_image":[{"width":750,"height":441,"url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg","type":"image\/jpeg"}],"author":"Portovenere","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ghportovenere","twitter_site":"@ghportovenere","twitter_misc":{"Scritto da":"Portovenere","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/#article","isPartOf":{"@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/"},"author":{"name":"Portovenere","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/person\/77b4e306e5541ddeea527c99f7a03e89"},"headline":"L&#8217;ode di Eugenio Montale a Portovenere","datePublished":"2015-11-27T09:42:21+00:00","dateModified":"2023-05-17T13:00:39+00:00","mainEntityOfPage":{"@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/"},"wordCount":320,"commentCount":1,"publisher":{"@id":"https:\/\/discoverportovenere.com\/it\/#organization"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/#primaryimage"},"thumbnailUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg","keywords":["eugenio montale","poesia","portovenere"],"articleSection":["Poesia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/","url":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/","name":"Portovenere Nella Poesia: L'Ode Di Eugenio Montale","isPartOf":{"@id":"https:\/\/discoverportovenere.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/#primaryimage"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/#primaryimage"},"thumbnailUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg","datePublished":"2015-11-27T09:42:21+00:00","dateModified":"2023-05-17T13:00:39+00:00","description":"La poesia di Eugenio Montale rende l'idea delle sensazioni che proverai arrivando nel borgo sospeso tra natura, storia, mito e bellezza!","breadcrumb":{"@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/#primaryimage","url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg","width":750,"height":441},{"@type":"BreadcrumbList","@id":"https:\/\/discoverportovenere.com\/it\/poesia-eugenio-montale-portovenere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/discoverportovenere.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;ode di Eugenio Montale a Portovenere"}]},{"@type":"WebSite","@id":"https:\/\/discoverportovenere.com\/it\/#website","url":"https:\/\/discoverportovenere.com\/it\/","name":"Discover Portovenere Blog","description":"between Liguria & Tuscany","publisher":{"@id":"https:\/\/discoverportovenere.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/discoverportovenere.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/discoverportovenere.com\/it\/#organization","name":"Discover Portovenere - Grand Hotel Portovenere","url":"https:\/\/discoverportovenere.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/discover-portovenere-liguria-tuscany-700.png","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/discover-portovenere-liguria-tuscany-700.png","width":700,"height":92,"caption":"Discover Portovenere - Grand Hotel Portovenere"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grandhotelportovenere","https:\/\/x.com\/ghportovenere","https:\/\/www.instagram.com\/ghportovenere\/","https:\/\/www.linkedin.com\/company\/grand-hotel-portovenere","https:\/\/www.youtube.com\/c\/Portoveneregrand"]},{"@type":"Person","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/person\/77b4e306e5541ddeea527c99f7a03e89","name":"Portovenere","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","url":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","caption":"Portovenere"},"description":"5-star hotel in Portovenere, between the Bay of Poets and Cinque Terre in Liguria. Explore this beautiful Italian destination with Discover Portovenere Blog.","sameAs":["https:\/\/www.portoveneregrand.com\/","https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761","https:\/\/www.instagram.com\/ghportovenere\/","https:\/\/x.com\/https:\/\/twitter.com\/ghportovenere"]}]}},"jetpack_featured_media_url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5GNh5-1HR","jetpack-related-posts":[{"id":700,"url":"https:\/\/discoverportovenere.com\/portovenere-poem-eugenio-montale\/","url_meta":{"origin":6563,"position":0},"title":"Portovenere in Poetry: an ode by Eugenio Montale","author":"Portovenere","date":"27 Novembre 2015","format":false,"excerpt":"Portovenere and the Gulf of La Spezia have bewitched innumerable writers throughout time \u2013 to the extent that the area is today known as the Bay of Poets. One artist in particular captured the essence of the town in a poem dedicated to Portovenere. Eugenio Montale (1896 \u2013 1981) was\u2026","rel":"","context":"In &quot;Poetry&quot;","block_context":{"text":"Poetry","link":"https:\/\/discoverportovenere.com\/category\/poetry\/"},"img":{"alt_text":"Portovenere Poem by Eugenio Montale","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2015\/11\/Portovenere-Poem-by-Eugenio-Montale.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":5979,"url":"https:\/\/discoverportovenere.com\/it\/storia-di-portovenere\/","url_meta":{"origin":6563,"position":1},"title":"Storia di Portovenere","author":"Portovenere","date":"18 Maggio 2021","format":false,"excerpt":"\u201cA quelli che giungono dal mare appare nel lido il porto di Venere e qui - nei colli che ammanta l'ulivo \u00e8 fama che anche Minerva scordasse per tanta dolcezza Atene - sua patria\u201d \u00c8 cos\u00ec che Petrarca, letterato e poeta rinascimentale italiano, celebr\u00f2 Porto Venere nel 1338, legando il\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2016\/03\/Ancient-Portovenere-Liguria.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2016\/03\/Ancient-Portovenere-Liguria.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2016\/03\/Ancient-Portovenere-Liguria.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2016\/03\/Ancient-Portovenere-Liguria.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6465,"url":"https:\/\/discoverportovenere.com\/it\/9-poeti-che-amarono-il-golfo-dei-poeti\/","url_meta":{"origin":6563,"position":2},"title":"9 poeti che amarono il Golfo dei Poeti","author":"Portovenere","date":"16 Novembre 2022","format":false,"excerpt":"Si chiamava Luna al tempo dell\u2019invasione romana, poi Porto lunense, Portus Veneris, Ericis portus, Gurfum Spezia e infine Golfo della Spezia. Ma da quando \u00e8 noto anche come Golfo dei Poeti? Dall\u2019estate del 1910, quando il drammaturgo fiorentino Sem Benelli, tenendo l\u2019orazione funebre alle esequie del suo amico scienziato e\u2026","rel":"","context":"In &quot;Arte&quot;","block_context":{"text":"Arte","link":"https:\/\/discoverportovenere.com\/it\/categoria\/arte\/"},"img":{"alt_text":"liguria poets writers golf of poets spezia","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":8296,"url":"https:\/\/discoverportovenere.com\/it\/parco-letterario-percy-shelley-san-terenzo\/","url_meta":{"origin":6563,"position":3},"title":"Il Parco Letterario Percy B. Shelley a San Terenzo","author":"Portovenere","date":"10 Settembre 2024","format":false,"excerpt":"Il Parco Letterario \u201cPercy B. Shelley \u2013 San Terenzo e il Golfo dei Poeti\u201d \u00e8 stato inaugurato a luglio 2024, entrando ufficialmente a far parte della prestigiosa rete nazionale dei Parchi Letterari\u00ae. Il Parco, ideato in occasione del bicentenario dalla morte del poeta Percy Bysshe Shelley, avvenuta nel 1822, si\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"san terenzo shelley literary park in the gulf of poets (1)","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/09\/san-terenzo-shelley-literary-park-in-the-gulf-of-poets-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/09\/san-terenzo-shelley-literary-park-in-the-gulf-of-poets-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/09\/san-terenzo-shelley-literary-park-in-the-gulf-of-poets-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/09\/san-terenzo-shelley-literary-park-in-the-gulf-of-poets-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/09\/san-terenzo-shelley-literary-park-in-the-gulf-of-poets-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6597,"url":"https:\/\/discoverportovenere.com\/it\/cosa-fare-giornata-pioggia-portovenere\/","url_meta":{"origin":6563,"position":4},"title":"7 cose da fare a Portovenere quando piove","author":"Portovenere","date":"3 Febbraio 2017","format":false,"excerpt":"\u201cCerto, doveva piovere e quant'altro, ma come potevo permettere che qualche goccia rovinasse la nostra avventura? Se Byron \u00e8 riuscito a sopportare 7,5 chilometri di Mar Mediterraneo, allora s\u00ec, possiamo sopportare un po' di pioggia.\u201d [Georgette Jupe in 36 Hours in Portovenere] Una delle cose che desideriamo pi\u00f9 fervidamente quando\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2017\/02\/rainy-day-gulf-of-poets.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2017\/02\/rainy-day-gulf-of-poets.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2017\/02\/rainy-day-gulf-of-poets.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2017\/02\/rainy-day-gulf-of-poets.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2017\/02\/rainy-day-gulf-of-poets.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2017\/02\/rainy-day-gulf-of-poets.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":6520,"url":"https:\/\/discoverportovenere.com\/it\/portofino-portovenere-confronto-mete-glamour\/","url_meta":{"origin":6563,"position":5},"title":"Portofino e Portovenere: due mete glamour a confronto","author":"Portovenere","date":"19 Marzo 2020","format":false,"excerpt":"Portofino e Portovenere sono due destinazioni di lusso italiane tanto simili quanto diverse. Mettiamo a confronto questi splendidi borghi della Riviera italiana. Paesaggio, Natura ed Escursioni Sia Portofino che Portovenere sono piccoli borghi di pescatori caratterizzati da porti pittoreschi, immersi in lussureggianti parchi naturali - rispettivamente il Parco Nazionale di\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/portofino-and-portovenere-comparison-luxury-destinations.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/portofino-and-portovenere-comparison-luxury-destinations.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/portofino-and-portovenere-comparison-luxury-destinations.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/portofino-and-portovenere-comparison-luxury-destinations.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2020\/03\/portofino-and-portovenere-comparison-luxury-destinations.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts\/6563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/comments?post=6563"}],"version-history":[{"count":0,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts\/6563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/media\/4992"}],"wp:attachment":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/media?parent=6563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/categories?post=6563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/tags?post=6563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}