{"id":7929,"date":"2024-06-06T09:25:05","date_gmt":"2024-06-06T07:25:05","guid":{"rendered":"https:\/\/discoverportovenere.com\/?p=7929"},"modified":"2025-06-26T16:22:21","modified_gmt":"2025-06-26T14:22:21","slug":"musica-muscoli-aperitivi-porto-venere","status":"publish","type":"post","link":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/","title":{"rendered":"Musica, Muscoli e Aperitivi sulla terrazza pi\u00f9 bella di Portovenere"},"content":{"rendered":"\n<p>Il Venus Bar, con la sua spettacolare terrazza che si affaccia sul porticciolo di <a href=\"https:\/\/discoverportovenere.com\/it\/cose-da-fare-a-portovenere\/\">Portovenere<\/a> e sull&#8217;<a href=\"https:\/\/discoverportovenere.com\/it\/natura-escursioni-isola-palmaria\/\">Isola Palmaria<\/a>, \u00e8 il luogo ideale per vivere esperienze gastronomiche uniche e godersi concerti di musica dal vivo. Situato vicino alle Cinque Terre, \u00e8 perfetto per chi cerca buon cibo e ottima musica in un&#8217;atmosfera mozzafiato.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cocktail e mocktail estivi<\/h2>\n\n\n\n<p>I mixologist del <a href=\"https:\/\/www.palmariarestaurant.com\/it\/venus-bar\" target=\"_blank\" rel=\"noreferrer noopener\">Venus Bar<\/a> sono veri artisti della creazione di cocktail, sempre pronti a inventare nuovi drink per mantenere il men\u00f9 fresco e dinamico.<\/p>\n\n\n\n<p>Tra i protagonisti del 2025 c&#8217;\u00e8 il wine cocktail Ca du Kir, preparato con Cr\u00e8me de Cassis e Vermentino locale. \u00c8 una rivisitazione del Kir, il celebre cocktail nato nel 1950 in Borgogna.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"830\" height=\"1200\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/cocktail-bar-portovenere-panorama-1-830x1200.jpg\" alt=\"venus bar cocktails in portovenere\" class=\"wp-image-7909\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/cocktail-bar-portovenere-panorama-1-830x1200.jpg 830w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/cocktail-bar-portovenere-panorama-1-242x350.jpg 242w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/cocktail-bar-portovenere-panorama-1-768x1110.jpg 768w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/cocktail-bar-portovenere-panorama-1-1063x1536.jpg 1063w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/cocktail-bar-portovenere-panorama-1.jpg 1080w\" sizes=\"auto, (max-width: 830px) 100vw, 830px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La carta del Venus Bar riscopre grandi classici, presenta scelte originali e una vasta scelta di opzioni no alcohol.<\/p>\n\n\n\n<p>Alcuni esempi?<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vinegar Negroni, un twist interessante al classico Negroni. Presenta un Vermouth che fa un passaggio in botti utilizzate precedentemente per l\u2019aceto balsamico. Il gusto \u00e8 quindi qualcosa di unico!<\/li>\n\n\n\n<li>Il Mexcalita de Juar\u00e9z, che prende ispirazione dal grande Tommy\u2019s Margarita, per un tocco di Messico a Portovenere. L\u2019aggiunta del Cordiale al Palo Santo dona un sapore molto particolare che si combina perfettamente con le note affumicate di questo drink.<\/li>\n\n\n\n<li>Il Basil Smash 0.0 che mette in risalto una delle <a href=\"https:\/\/discoverportovenere.com\/it\/prodotti-tipici-cinque-terre-golfo-poeti\/\">principali materie prime del Golfo dei Poeti<\/a>, il delizioso e fresco basilico. Esalta l\u2019estate, tanto gusto e 0 alcohol!&nbsp;<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/alquimico-cocktail.jpg\" alt=\"\" class=\"wp-image-7907\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/alquimico-cocktail.jpg 720w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/alquimico-cocktail-263x350.jpg 263w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Muscoli per una buona causa<\/h2>\n\n\n\n<p>Sunset Muscoli \u00e8 l\u2019evento gastronomico solidale che il <a href=\"https:\/\/www.portoveneregrand.com\/it\" target=\"_blank\" rel=\"noreferrer noopener\">Grand Hotel Portovenere<\/a> organizza ogni estate.<\/p>\n\n\n\n<p>Durante queste serate, potrai gustare i tipici muscoli del <a href=\"https:\/\/discoverportovenere.com\/it\/golfo-dei-poeti\/\">Golfo dei Poeti<\/a> preparati in diverse varianti dalla brigata del Palmaria Restaurant, il tutto accompagnato da una selezione di vini locali.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1200\" data-id=\"7912\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-1-1-900x1200.jpg\" alt=\"typical muscoli (mussels) from the Gulf Of Poets \" class=\"wp-image-7912\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-1-1-900x1200.jpg 900w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-1-1-263x350.jpg 263w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-1-1-768x1024.jpg 768w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-1-1.jpg 1080w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1200\" data-id=\"7914\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-2-1-960x1200.jpg\" alt=\"typical muscoli (mussels) from Portovenere\" class=\"wp-image-7914\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-2-1-960x1200.jpg 960w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-2-1-280x350.jpg 280w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-2-1-768x960.jpg 768w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-2-1.jpg 1080w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1200\" data-id=\"7916\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-3-1-960x1200.jpg\" alt=\"mussels for a good cause\" class=\"wp-image-7916\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-3-1-960x1200.jpg 960w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-3-1-280x350.jpg 280w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-3-1-768x960.jpg 768w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/mussels-tasting-in-portovenere-3-1.jpg 1080w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Questi appuntamenti si tengono solitamente ogni gioved\u00ec da met\u00e0 giugno a met\u00e0 settembre (escluso agosto).<\/p>\n\n\n\n<p>Per saperne di pi\u00f9, leggi <a href=\"https:\/\/discoverportovenere.com\/it\/sunset-muscoli-iniziativa-solidale-portovenere\/\">Sunset Muscoli tra gusto e iniziative solidali<\/a>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Concerti di musica dal vivo a Portovenere<\/h2>\n\n\n\n<p>Il Palmaria Restaurant e il Venus Bar propongono un ricco calendario di concerti di musica dal vivo, aperitivi a tema e cene degustazione.<\/p>\n\n\n\n<p>Tra giugno e settembre, la terrazza diventa il palco di una serie di concerti di musica dal vivo, perfetti mentre si sorseggia cocktail all\u2019orario dell\u2019aperitivo o si sceglie di cenare vista mare a Portovenere!<\/p>\n\n\n\n<p>Ecco il calendario degli eventi 2025:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"867\" data-attachment-id=\"8632\" data-permalink=\"https:\/\/discoverportovenere.com\/it\/eventi-estate-portovenere-golfo-dei-poeti\/eventi-portovenere-2025-musica-dal-vivo-1-2\/\" data-orig-file=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-scaled.jpg\" data-orig-size=\"2560,1849\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"eventi-portovenere 2025-musica-dal vivo (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-1200x867.jpg\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-1200x867.jpg\" alt=\"eventi con musica dal vivo estate portovenere\" class=\"wp-image-8632\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-1200x867.jpg 1200w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-350x253.jpg 350w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-768x555.jpg 768w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-1536x1109.jpg 1536w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/eventi-portovenere-2025-musica-dal-vivo-1-2048x1479.jpg 2048w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Per ulteriori informazioni, <a href=\"https:\/\/www.palmariarestaurant.com\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\">visita il sito ufficiale del Palmaria Restaurant Portovenere<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Venus Bar, con la sua spettacolare terrazza che si affaccia sul porticciolo di Portovenere e sull&#8217;Isola Palmaria, \u00e8 il luogo ideale per vivere esperienze&hellip;<\/p>\n","protected":false},"author":2,"featured_media":7925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[187],"tags":[182,235,256,257,270,286,322],"class_list":["post-7929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-estate","tag-eventi","tag-musica-jazz","tag-la-spezia-it","tag-musica","tag-portovenere","tag-venus-bar-it","post-grid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Musica, Muscoli e Aperitivi sulla Terrazza pi\u00f9 Bella di Portovenere<\/title>\n<meta name=\"description\" content=\"Vicino alle Cinque Terre, il Venus Bar, con la sua terrazza, \u00e8 perfetto per chi cerca buon cibo e musica in un&#039;atmosfera mozzafiato\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Musica, Muscoli e Aperitivi sulla Terrazza pi\u00f9 Bella di Portovenere\" \/>\n<meta property=\"og:description\" content=\"Vicino alle Cinque Terre, il Venus Bar, con la sua terrazza, \u00e8 perfetto per chi cerca buon cibo e musica in un&#039;atmosfera mozzafiato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/\" \/>\n<meta property=\"og:site_name\" content=\"Discover Portovenere Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grandhotelportovenere\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T07:25:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T14:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/06\/live-music-concerts-in-portovenere-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portovenere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ghportovenere\" \/>\n<meta name=\"twitter:site\" content=\"@ghportovenere\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portovenere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/\"},\"author\":{\"name\":\"Portovenere\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/person\\\/77b4e306e5541ddeea527c99f7a03e89\"},\"headline\":\"Musica, Muscoli e Aperitivi sulla terrazza pi\u00f9 bella di Portovenere\",\"datePublished\":\"2024-06-06T07:25:05+00:00\",\"dateModified\":\"2025-06-26T14:22:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/\"},\"wordCount\":402,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/live-music-concerts-in-portovenere-1.jpg\",\"keywords\":[\"estate\",\"eventi\",\"jazz\",\"la spezia\",\"musica\",\"portovenere\",\"venus bar\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/\",\"name\":\"Musica, Muscoli e Aperitivi sulla Terrazza pi\u00f9 Bella di Portovenere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/live-music-concerts-in-portovenere-1.jpg\",\"datePublished\":\"2024-06-06T07:25:05+00:00\",\"dateModified\":\"2025-06-26T14:22:21+00:00\",\"description\":\"Vicino alle Cinque Terre, il Venus Bar, con la sua terrazza, \u00e8 perfetto per chi cerca buon cibo e musica in un'atmosfera mozzafiato\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/live-music-concerts-in-portovenere-1.jpg\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/live-music-concerts-in-portovenere-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"live music concerts in portovenere\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/musica-muscoli-aperitivi-porto-venere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Musica, Muscoli e Aperitivi sulla terrazza pi\u00f9 bella di Portovenere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\",\"name\":\"Discover Portovenere Blog\",\"description\":\"between Liguria & Tuscany\",\"publisher\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\",\"name\":\"Discover Portovenere - Grand Hotel Portovenere\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/discover-portovenere-liguria-tuscany-700.png\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/discover-portovenere-liguria-tuscany-700.png\",\"width\":700,\"height\":92,\"caption\":\"Discover Portovenere - Grand Hotel Portovenere\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grandhotelportovenere\",\"https:\\\/\\\/x.com\\\/ghportovenere\",\"https:\\\/\\\/www.instagram.com\\\/ghportovenere\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/grand-hotel-portovenere\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Portoveneregrand\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/person\\\/77b4e306e5541ddeea527c99f7a03e89\",\"name\":\"Portovenere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"caption\":\"Portovenere\"},\"description\":\"5-star hotel in Portovenere, between the Bay of Poets and Cinque Terre in Liguria. Explore this beautiful Italian destination with Discover Portovenere Blog.\",\"sameAs\":[\"https:\\\/\\\/www.portoveneregrand.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Grand-Hotel-Portovenere\\\/158392434188761\",\"https:\\\/\\\/www.instagram.com\\\/ghportovenere\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ghportovenere\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Musica, Muscoli e Aperitivi sulla Terrazza pi\u00f9 Bella di Portovenere","description":"Vicino alle Cinque Terre, il Venus Bar, con la sua terrazza, \u00e8 perfetto per chi cerca buon cibo e musica in un'atmosfera mozzafiato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/","og_locale":"it_IT","og_type":"article","og_title":"Musica, Muscoli e Aperitivi sulla Terrazza pi\u00f9 Bella di Portovenere","og_description":"Vicino alle Cinque Terre, il Venus Bar, con la sua terrazza, \u00e8 perfetto per chi cerca buon cibo e musica in un'atmosfera mozzafiato","og_url":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/","og_site_name":"Discover Portovenere Blog","article_publisher":"https:\/\/www.facebook.com\/grandhotelportovenere","article_author":"https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761","article_published_time":"2024-06-06T07:25:05+00:00","article_modified_time":"2025-06-26T14:22:21+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/06\/live-music-concerts-in-portovenere-1.jpg","type":"image\/jpeg"}],"author":"Portovenere","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ghportovenere","twitter_site":"@ghportovenere","twitter_misc":{"Scritto da":"Portovenere","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/#article","isPartOf":{"@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/"},"author":{"name":"Portovenere","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/person\/77b4e306e5541ddeea527c99f7a03e89"},"headline":"Musica, Muscoli e Aperitivi sulla terrazza pi\u00f9 bella di Portovenere","datePublished":"2024-06-06T07:25:05+00:00","dateModified":"2025-06-26T14:22:21+00:00","mainEntityOfPage":{"@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/"},"wordCount":402,"commentCount":0,"publisher":{"@id":"https:\/\/discoverportovenere.com\/it\/#organization"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/#primaryimage"},"thumbnailUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/06\/live-music-concerts-in-portovenere-1.jpg","keywords":["estate","eventi","jazz","la spezia","musica","portovenere","venus bar"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/","url":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/","name":"Musica, Muscoli e Aperitivi sulla Terrazza pi\u00f9 Bella di Portovenere","isPartOf":{"@id":"https:\/\/discoverportovenere.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/#primaryimage"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/#primaryimage"},"thumbnailUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/06\/live-music-concerts-in-portovenere-1.jpg","datePublished":"2024-06-06T07:25:05+00:00","dateModified":"2025-06-26T14:22:21+00:00","description":"Vicino alle Cinque Terre, il Venus Bar, con la sua terrazza, \u00e8 perfetto per chi cerca buon cibo e musica in un'atmosfera mozzafiato","breadcrumb":{"@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/#primaryimage","url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/06\/live-music-concerts-in-portovenere-1.jpg","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/06\/live-music-concerts-in-portovenere-1.jpg","width":1920,"height":1080,"caption":"live music concerts in portovenere"},{"@type":"BreadcrumbList","@id":"https:\/\/discoverportovenere.com\/it\/musica-muscoli-aperitivi-porto-venere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/discoverportovenere.com\/it\/"},{"@type":"ListItem","position":2,"name":"Musica, Muscoli e Aperitivi sulla terrazza pi\u00f9 bella di Portovenere"}]},{"@type":"WebSite","@id":"https:\/\/discoverportovenere.com\/it\/#website","url":"https:\/\/discoverportovenere.com\/it\/","name":"Discover Portovenere Blog","description":"between Liguria & Tuscany","publisher":{"@id":"https:\/\/discoverportovenere.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/discoverportovenere.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/discoverportovenere.com\/it\/#organization","name":"Discover Portovenere - Grand Hotel Portovenere","url":"https:\/\/discoverportovenere.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/discover-portovenere-liguria-tuscany-700.png","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/discover-portovenere-liguria-tuscany-700.png","width":700,"height":92,"caption":"Discover Portovenere - Grand Hotel Portovenere"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grandhotelportovenere","https:\/\/x.com\/ghportovenere","https:\/\/www.instagram.com\/ghportovenere\/","https:\/\/www.linkedin.com\/company\/grand-hotel-portovenere","https:\/\/www.youtube.com\/c\/Portoveneregrand"]},{"@type":"Person","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/person\/77b4e306e5541ddeea527c99f7a03e89","name":"Portovenere","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","url":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","caption":"Portovenere"},"description":"5-star hotel in Portovenere, between the Bay of Poets and Cinque Terre in Liguria. Explore this beautiful Italian destination with Discover Portovenere Blog.","sameAs":["https:\/\/www.portoveneregrand.com\/","https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761","https:\/\/www.instagram.com\/ghportovenere\/","https:\/\/x.com\/https:\/\/twitter.com\/ghportovenere"]}]}},"jetpack_featured_media_url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/06\/live-music-concerts-in-portovenere-1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5GNh5-23T","jetpack-related-posts":[{"id":7104,"url":"https:\/\/discoverportovenere.com\/it\/ferragosto-porto-venere\/","url_meta":{"origin":7929,"position":0},"title":"Ferragosto a Portovenere","author":"Portovenere","date":"29 Luglio 2025","format":false,"excerpt":"\u00c8 la festa pi\u00f9 attesa della stagione e l'apice dello splendore estivo! Lo sapevi che il Ferragosto ha origini nella storia dell'Antica Roma che poi si sono intrecciate con la tradizione cattolica? Il nome della festa di Ferragosto deriva dal latino feriae Augusti, in onore di Ottaviano Augusto, primo imperatore\u2026","rel":"","context":"In &quot;Eventi&quot;","block_context":{"text":"Eventi","link":"https:\/\/discoverportovenere.com\/it\/categoria\/eventi\/"},"img":{"alt_text":"Ferragosto Portovenere","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/07\/ferragosto-portovenere.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/07\/ferragosto-portovenere.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/07\/ferragosto-portovenere.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/07\/ferragosto-portovenere.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/07\/ferragosto-portovenere.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7018,"url":"https:\/\/discoverportovenere.com\/it\/eventi-estate-portovenere-golfo-dei-poeti\/","url_meta":{"origin":7929,"position":1},"title":"Eventi estate 2025 a Portovenere e nel Golfo dei Poeti","author":"Portovenere","date":"14 Giugno 2025","format":false,"excerpt":"L\u2019estate \u00e8 un\u2019ottima stagione per visitare Portovenere e la provincia di La Spezia, soprattutto per chi cerca destinazioni pi\u00f9 tranquille sulla riviera ligure. Dai festival culturali alle avventure all\u2019aria aperta, durante l'estate c\u2019\u00e8 qualcosa per tutti i gusti! Scopri alcuni degli eventi pi\u00f9 emozionanti dell\u2019estate 2025 tra Portovenere e nel\u2026","rel":"","context":"In &quot;Eventi&quot;","block_context":{"text":"Eventi","link":"https:\/\/discoverportovenere.com\/it\/categoria\/eventi\/"},"img":{"alt_text":"summer events in portovenere lerici spezia (1)","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7271,"url":"https:\/\/discoverportovenere.com\/it\/viaggio-sensoriale-tra-portovenere-cilento\/","url_meta":{"origin":7929,"position":2},"title":"Un viaggio sensoriale tra Portovenere e il Cilento","author":"Portovenere","date":"19 Settembre 2023","format":false,"excerpt":"Beside \u00e8 un gin artigianale creato con botaniche fresche, tra cui foglie selezionate di basilico, fiori di zagara, cedro e salvia, provenienti dal Cilento e dalla riviera ligure tra Portovenere e Cinque Terre. Cocktail originali con Beside Gin al Venus Bar di Portovenere L\u2019essenza \u00e8 stata studiata da Baldo Baldinini,\u2026","rel":"","context":"In &quot;Enogastronomia&quot;","block_context":{"text":"Enogastronomia","link":"https:\/\/discoverportovenere.com\/it\/categoria\/enogastronomia\/"},"img":{"alt_text":"gin cocktails and music in portovenere","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/09\/gin-in-portovenere-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/09\/gin-in-portovenere-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/09\/gin-in-portovenere-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/09\/gin-in-portovenere-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/09\/gin-in-portovenere-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/09\/gin-in-portovenere-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":7961,"url":"https:\/\/discoverportovenere.com\/it\/cocktail-con-vino-venus-bar\/","url_meta":{"origin":7929,"position":3},"title":"C\u00e0 du Kir: il Wine Cocktail di Portovenere con C\u00e0 du Ferr\u00e0","author":"Portovenere","date":"11 Giugno 2024","format":false,"excerpt":"Il mondo della mixology sta esplorando sempre nuove frontiere, tra cui l\u2019uso di vini fermi al posto dei tradizionali distillati per la creazione di originali \u201cwine cocktail\u201d. Questi cocktail con il vino hanno spesso protagonisti come il Vermentino, il Traminer, la Falanghina, il Chardonnay e il Greco. Si tratta di\u2026","rel":"","context":"In &quot;Enogastronomia&quot;","block_context":{"text":"Enogastronomia","link":"https:\/\/discoverportovenere.com\/it\/categoria\/enogastronomia\/"},"img":{"alt_text":"Italian Summer Wine Cocktail from Portovenere","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Italian-Summer-Wine-Cocktail-from-Portovenere.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Italian-Summer-Wine-Cocktail-from-Portovenere.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Italian-Summer-Wine-Cocktail-from-Portovenere.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Italian-Summer-Wine-Cocktail-from-Portovenere.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Italian-Summer-Wine-Cocktail-from-Portovenere.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Italian-Summer-Wine-Cocktail-from-Portovenere.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":6261,"url":"https:\/\/discoverportovenere.com\/it\/i-cocktail-del-marmo\/","url_meta":{"origin":7929,"position":4},"title":"I cocktail del marmo","author":"Portovenere","date":"30 Luglio 2023","format":false,"excerpt":"I mixologist del Venus Bar, il panoramico e originale cocktail bar del Grand Hotel Portovenere, hanno ideato tre cocktail per rendere omaggio alla tradizione del marmo tra Liguria e Toscana! I cocktail prendono il nome da due degli iconici marmi toscani, Bianco Carrara e Calacatta, e del marmo nero di\u2026","rel":"","context":"In &quot;Enogastronomia&quot;","block_context":{"text":"Enogastronomia","link":"https:\/\/discoverportovenere.com\/it\/categoria\/enogastronomia\/"},"img":{"alt_text":"marble inspired cocktails portovenere.jpg","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/marble-inspired-cocktails-portovenere.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/marble-inspired-cocktails-portovenere.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/marble-inspired-cocktails-portovenere.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/marble-inspired-cocktails-portovenere.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/marble-inspired-cocktails-portovenere.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6240,"url":"https:\/\/discoverportovenere.com\/it\/sunset-muscoli-iniziativa-solidale-portovenere\/","url_meta":{"origin":7929,"position":5},"title":"Sunset Muscoli tra gusto e iniziative solidali","author":"Portovenere","date":"1 Luglio 2025","format":false,"excerpt":"Sunset Muscoli \u00e8 l\u2019evento gastronomico solidale organizzato ogni estate dal Grand Hotel Portovenere. In queste serate deliziose potrete degustare i tipici muscoli del Golfo dei Poeti preparati in diversi modi dalla brigata del Palmaria Restaurant, abbinati ai migliori vini locali. A volte il calendario prevede delle versioni alternative durante le\u2026","rel":"","context":"In &quot;Enogastronomia&quot;","block_context":{"text":"Enogastronomia","link":"https:\/\/discoverportovenere.com\/it\/categoria\/enogastronomia\/"},"img":{"alt_text":"sunset mussels portovenere la spezia (1)","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/sunset-mussels-portovenere-la-spezia-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/sunset-mussels-portovenere-la-spezia-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/sunset-mussels-portovenere-la-spezia-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/07\/sunset-mussels-portovenere-la-spezia-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts\/7929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/comments?post=7929"}],"version-history":[{"count":0,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts\/7929\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/media\/7925"}],"wp:attachment":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/media?parent=7929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/categories?post=7929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/tags?post=7929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}