{"id":7999,"date":"2024-06-26T14:45:53","date_gmt":"2024-06-26T12:45:53","guid":{"rendered":"https:\/\/discoverportovenere.com\/?p=7999"},"modified":"2024-06-26T15:06:42","modified_gmt":"2024-06-26T13:06:42","slug":"storia-musica-la-spezia","status":"publish","type":"post","link":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/","title":{"rendered":"La Spezia: un viaggio tra musica classica, jazz e folk"},"content":{"rendered":"\n<p><a href=\"https:\/\/discoverportovenere.com\/it\/cosa-vedere-la-spezia\/\">La Spezia<\/a>, nel <a href=\"https:\/\/discoverportovenere.com\/it\/golfo-dei-poeti\/\">Golfo dei Poeti<\/a>, vanta una ricca storia musicale che attraversa secoli, partendo dai compositori classici fino ad arrivare al jazz e al revival della musica popolare.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La Spezia e la musica classica: i compositori del Golfo dei Poeti<\/h2>\n\n\n\n<p>Il primo e pi\u00f9 antico musicista spezzino documentato \u00e8 Giovanni Agostino Casone, frate dei Minori Osservanti Riformati di San Francesco. Intorno al 1600, Casone riorganizz\u00f2 gli inni sacri in un poderoso trattato.<\/p>\n\n\n\n<p>Giambattista Vissei, nato a <a href=\"https:\/\/discoverportovenere.com\/it\/guida-viaggio-definitiva-portovenere\/\">Porto Venere<\/a> nel 1766, si distinse come compositore di varie opere tra cui un Sestetto per serenata per quartetto d\u2019archi, corno e clarinetto. Fu applaudito persino da Napoleone Bonaparte che ebbe occasione di ascoltarlo a Genova.<\/p>\n\n\n\n<p>Stefano Santo Bruni, nato nel 1801 a Bastremoli in provincia della Spezia, divenne famoso per le sue composizioni sacre e profane, nonch\u00e9 come insegnante di musica. Tra gli allievi ebbe la marchesa Virginia Oldoini.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"480\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Carlo-Alfredo-Mussinelli-La-Spezia-musician.jpg\" alt=\"Carlo Mussinelli - composer and pianist from La Spezia\" class=\"wp-image-7970\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Carlo-Alfredo-Mussinelli-La-Spezia-musician.jpg 500w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Carlo-Alfredo-Mussinelli-La-Spezia-musician-350x336.jpg 350w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\"><em>Carlo Alfredo Mussinelli. La citt\u00e0 della Spezia insign\u00ec della medaglia d&#8217;oro il &#8220;cieco veggente&#8221;, come defin\u00ec Giovanni Pascoli.<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La Spezia ha dato i natali anche a Carlo Mussinelli nel 1871, che, nonostante la cecit\u00e0, si dedic\u00f2 con successo alla musica, diventando un noto compositore e pianista, molto stimato anche da Giovanni Pascoli.<\/p>\n\n\n\n<p>Giovanni Pagella, nato a <a href=\"https:\/\/discoverportovenere.com\/it\/borghi-marinari-le-grazie-fezzano\/\">Le Grazie<\/a> nel 1872, fu un sacerdote e compositore di musica sacra, ammirato anche dal celebre compositore e direttore d&#8217;orchestra Pietro Mascagni.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-medium is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"350\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Domenico-Cortopassi-Rusticanella-259x350.jpg\" alt=\"opera by Domenico Cortopassi\" class=\"wp-image-7981\" style=\"width:200px\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Domenico-Cortopassi-Rusticanella-259x350.jpg 259w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Domenico-Cortopassi-Rusticanella.jpg 444w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" \/><\/figure>\n<\/div>\n\n\n<p>Domenico Cortopassi, nato a <a href=\"https:\/\/discoverportovenere.com\/it\/cose-vedere-nella-splendida-sarzana\/\">Sarzana<\/a> nel 1875, si afferm\u00f2 come direttore d&#8217;orchestra e organista, famoso per le sue operette e messe natalizie.<\/p>\n\n\n\n<p>Cortopassi studi\u00f2 a <a href=\"https:\/\/discoverportovenere.com\/it\/museo-zecca-lucca\/\">Lucca<\/a>, dove ebbe la fortuna di avere come insegnanti Carlo Angeloni e <a href=\"https:\/\/discoverportovenere.com\/it\/museo-giacomo-puccini-festival\/\">Giacomo Puccini<\/a> .<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La Spezia e il Jazz<\/h2>\n\n\n\n<p>Nel 1969, La Spezia divenne la culla del <a href=\"https:\/\/discoverportovenere.com\/it\/festival-jazz-spezia\/\">Festival Internazionale del Jazz<\/a>, il pi\u00f9 longevo d\u2019Italia.<\/p>\n\n\n\n<p>Tra i suoi ideatori e fondatori c\u2019era Tiberio Nicola, nato nel 1931 a Villafranca Lunigiana e poi trasferitosi a La Spezia. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"428\" data-attachment-id=\"8002\" data-permalink=\"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/tiberio-nicola-jazz-spezia\/\" data-orig-file=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Tiberio-Nicola-Jazz-Spezia.jpeg\" data-orig-size=\"640,428\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Tiberio Nicola Jazz Spezia\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Tiberio-Nicola-Jazz-Spezia.jpeg\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Tiberio-Nicola-Jazz-Spezia.jpeg\" alt=\"Tiberio Nicola Jazz Spezia\" class=\"wp-image-8002\" style=\"width:500px\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Tiberio-Nicola-Jazz-Spezia.jpeg 640w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Tiberio-Nicola-Jazz-Spezia-350x234.jpeg 350w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-element-caption\"><em>Tiberio Nicola, detto \u201cIl Tibe\u201d<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Fin da bambino, Tiberio suonava il violino e rimaneva incantato dalla musica. Tuttavia, la guerra interruppe la sua carriera da violinista.<\/p>\n\n\n\n<p>Probabilmente, la sua passione per il jazz nacque durante il servizio militare a Roma nell&#8217;Aeronautica. Tornato a La Spezia, si un\u00ec a un gruppo di giovani appassionati di jazz, formando il Circolo Amici del Jazz. Poco dopo, lanciarono il festival.<\/p>\n\n\n\n<p>Da allora, molte star internazionali, come Keith Jarrett, Chet Baker, Charles Mingus e Michel Petrucciani, sono state ospiti del festival, rendendolo uno degli appuntamenti storici del jazz europeo.<\/p>\n\n\n\n<p>La passione per il jazz a La Spezia non si limita ai festival: Amazon ha classificato la citt\u00e0 come quella con il maggior consumo di jazz e blues in Italia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"307\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/La-Spezia-Big-Band.jpg\" alt=\"La Spezia Jazz Band\" class=\"wp-image-7973\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/La-Spezia-Big-Band.jpg 680w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/La-Spezia-Big-Band-350x158.jpg 350w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><figcaption class=\"wp-element-caption\"><em>La Spezia Big Band al Teatro Civico Della Spezia (foto di Bionducci)<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La Spezia ha anche avuto la sua orchestra jazz, La Spezia Big Band, attiva dal 1976 al 1989. La formazione, composta principalmente da musicisti spezzini, ha partecipato a varie edizioni del Festival Internazionale del Jazz, esibendosi sotto la guida di musicisti come Luciano Imparato e Bruno Tommaso.<\/p>\n\n\n\n<p>Altro noto compositore e trombettista spezzino \u00e8 <a href=\"https:\/\/discoverportovenere.com\/it\/playlist-musicale-lorenzo-cimino\/\">Lorenzo Cimino<\/a>, che \u00e8 anche direttore artistico dello Spezia Jazz Festival.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Musica folk del Levante ligure<\/h2>\n\n\n\n<p>La tradizione musicale della <a href=\"https:\/\/discoverportovenere.com\/it\/antica-luni-storia-archeologia\/\">Lunigiana<\/a> e del Levante ligure \u00e8 stata riscoperta negli anni &#8217;90 grazie a Tandarandan, gruppo musicale e associazione culturale di Mauro Manicardi.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"440\" src=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Tandarandan-libro-musica-folk-spezia.png\" alt=\"Tandarandan folk music from La Spezia\" class=\"wp-image-7976\" style=\"width:200px\" srcset=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Tandarandan-libro-musica-folk-spezia.png 300w, https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/Tandarandan-libro-musica-folk-spezia-239x350.png 239w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Manicardi era un organettista e appassionato cultore delle tradizioni popolari.<\/p>\n\n\n\n<p>Varie persone lo aiutarono a portare avanti il suo progetto, tra cui Bugelli, il cantastorie della Lunigiana; Edward Neill, etnomusicologo genovese; e Germano Cavalli, Direttore del Museo Etnografico di Villafranca.<\/p>\n\n\n\n<p>Con una attenta opera di ricerca sul campo, il progetto rilanci\u00f2 l&#8217;interesse per la musica tradizionale locale, coinvolgendo musicisti e gruppi di danza e utilizzando strumenti tradizionali come la ghironda, la piva e l\u2019organetto. Il repertorio di Tandarandan comprendeva gighe, valzer, mazurke, monfrine, canzoni e ballate.<\/p>\n\n\n\n<p>Tandarandan \u00e8 il personaggio di una filastrocca lunigianese citata a livello popolare.<\/p>\n\n\n\n<p><a href=\"https:\/\/discoverportovenere.com\/it\/scalo-crociera-la-spezia\/\">La Spezia<\/a>, con la sua ricca eredit\u00e0 musicale, dimostra una vivace e dinamica scena culturale, capace di attrarre e ispirare generazioni di artisti e appassionati!<\/p>\n\n\n\n<p><em>Fonti:<br>Ernesto Di Marino \u201cLa cultura musicale alla Spezia\u201d (1992)<br>Societ\u00e0 dei Concerti La Spezia \u201cI suoni della Lunigiana e del Levante ligure\u201d<br>Giorgio Pagano, Citt\u00e0 della Spezia<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Spezia, nel Golfo dei Poeti, vanta una ricca storia musicale che attraversa secoli, partendo dai compositori classici fino ad arrivare al jazz e al&hellip;<\/p>\n","protected":false},"author":2,"featured_media":7991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[183,189],"tags":[],"class_list":["post-7999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-storia","post-grid"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Spezia: Un Viaggio Tra Musica Classica, Jazz e Folk<\/title>\n<meta name=\"description\" content=\"Il Golfo Della Spezia ha una ricca storia musicale, dai compositori classici del 1600 al jazz fino al revival della musica popolare\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Spezia: Un Viaggio Tra Musica Classica, Jazz e Folk\" \/>\n<meta property=\"og:description\" content=\"Il Golfo Della Spezia ha una ricca storia musicale, dai compositori classici del 1600 al jazz fino al revival della musica popolare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/\" \/>\n<meta property=\"og:site_name\" content=\"Discover Portovenere Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grandhotelportovenere\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-26T12:45:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-26T13:06:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/musical-history-la-spezia-gulf-of-poets.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1201\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Portovenere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ghportovenere\" \/>\n<meta name=\"twitter:site\" content=\"@ghportovenere\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Portovenere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/\"},\"author\":{\"name\":\"Portovenere\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/person\\\/77b4e306e5541ddeea527c99f7a03e89\"},\"headline\":\"La Spezia: un viaggio tra musica classica, jazz e folk\",\"datePublished\":\"2024-06-26T12:45:53+00:00\",\"dateModified\":\"2024-06-26T13:06:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/\"},\"wordCount\":691,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/musical-history-la-spezia-gulf-of-poets.jpeg\",\"articleSection\":[\"Arte\",\"Storia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/\",\"name\":\"La Spezia: Un Viaggio Tra Musica Classica, Jazz e Folk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/musical-history-la-spezia-gulf-of-poets.jpeg\",\"datePublished\":\"2024-06-26T12:45:53+00:00\",\"dateModified\":\"2024-06-26T13:06:42+00:00\",\"description\":\"Il Golfo Della Spezia ha una ricca storia musicale, dai compositori classici del 1600 al jazz fino al revival della musica popolare\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/musical-history-la-spezia-gulf-of-poets.jpeg\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/musical-history-la-spezia-gulf-of-poets.jpeg\",\"width\":1800,\"height\":1201,\"caption\":\"musical history la spezia gulf of poets\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/storia-musica-la-spezia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Spezia: un viaggio tra musica classica, jazz e folk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\",\"name\":\"Discover Portovenere Blog\",\"description\":\"between Liguria & Tuscany\",\"publisher\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#organization\",\"name\":\"Discover Portovenere - Grand Hotel Portovenere\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/discover-portovenere-liguria-tuscany-700.png\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/discover-portovenere-liguria-tuscany-700.png\",\"width\":700,\"height\":92,\"caption\":\"Discover Portovenere - Grand Hotel Portovenere\"},\"image\":{\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/grandhotelportovenere\",\"https:\\\/\\\/x.com\\\/ghportovenere\",\"https:\\\/\\\/www.instagram.com\\\/ghportovenere\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/grand-hotel-portovenere\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Portoveneregrand\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/it\\\/#\\\/schema\\\/person\\\/77b4e306e5541ddeea527c99f7a03e89\",\"name\":\"Portovenere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"url\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"contentUrl\":\"https:\\\/\\\/discoverportovenere.com\\\/wp-content\\\/litespeed\\\/avatar\\\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278\",\"caption\":\"Portovenere\"},\"description\":\"5-star hotel in Portovenere, between the Bay of Poets and Cinque Terre in Liguria. Explore this beautiful Italian destination with Discover Portovenere Blog.\",\"sameAs\":[\"https:\\\/\\\/www.portoveneregrand.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Grand-Hotel-Portovenere\\\/158392434188761\",\"https:\\\/\\\/www.instagram.com\\\/ghportovenere\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ghportovenere\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Spezia: Un Viaggio Tra Musica Classica, Jazz e Folk","description":"Il Golfo Della Spezia ha una ricca storia musicale, dai compositori classici del 1600 al jazz fino al revival della musica popolare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/","og_locale":"it_IT","og_type":"article","og_title":"La Spezia: Un Viaggio Tra Musica Classica, Jazz e Folk","og_description":"Il Golfo Della Spezia ha una ricca storia musicale, dai compositori classici del 1600 al jazz fino al revival della musica popolare","og_url":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/","og_site_name":"Discover Portovenere Blog","article_publisher":"https:\/\/www.facebook.com\/grandhotelportovenere","article_author":"https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761","article_published_time":"2024-06-26T12:45:53+00:00","article_modified_time":"2024-06-26T13:06:42+00:00","og_image":[{"width":1800,"height":1201,"url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/musical-history-la-spezia-gulf-of-poets.jpeg","type":"image\/jpeg"}],"author":"Portovenere","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ghportovenere","twitter_site":"@ghportovenere","twitter_misc":{"Scritto da":"Portovenere","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/#article","isPartOf":{"@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/"},"author":{"name":"Portovenere","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/person\/77b4e306e5541ddeea527c99f7a03e89"},"headline":"La Spezia: un viaggio tra musica classica, jazz e folk","datePublished":"2024-06-26T12:45:53+00:00","dateModified":"2024-06-26T13:06:42+00:00","mainEntityOfPage":{"@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/"},"wordCount":691,"commentCount":0,"publisher":{"@id":"https:\/\/discoverportovenere.com\/it\/#organization"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/#primaryimage"},"thumbnailUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/musical-history-la-spezia-gulf-of-poets.jpeg","articleSection":["Arte","Storia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/","url":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/","name":"La Spezia: Un Viaggio Tra Musica Classica, Jazz e Folk","isPartOf":{"@id":"https:\/\/discoverportovenere.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/#primaryimage"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/#primaryimage"},"thumbnailUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/musical-history-la-spezia-gulf-of-poets.jpeg","datePublished":"2024-06-26T12:45:53+00:00","dateModified":"2024-06-26T13:06:42+00:00","description":"Il Golfo Della Spezia ha una ricca storia musicale, dai compositori classici del 1600 al jazz fino al revival della musica popolare","breadcrumb":{"@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/#primaryimage","url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/musical-history-la-spezia-gulf-of-poets.jpeg","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/musical-history-la-spezia-gulf-of-poets.jpeg","width":1800,"height":1201,"caption":"musical history la spezia gulf of poets"},{"@type":"BreadcrumbList","@id":"https:\/\/discoverportovenere.com\/it\/storia-musica-la-spezia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/discoverportovenere.com\/it\/"},{"@type":"ListItem","position":2,"name":"La Spezia: un viaggio tra musica classica, jazz e folk"}]},{"@type":"WebSite","@id":"https:\/\/discoverportovenere.com\/it\/#website","url":"https:\/\/discoverportovenere.com\/it\/","name":"Discover Portovenere Blog","description":"between Liguria & Tuscany","publisher":{"@id":"https:\/\/discoverportovenere.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/discoverportovenere.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/discoverportovenere.com\/it\/#organization","name":"Discover Portovenere - Grand Hotel Portovenere","url":"https:\/\/discoverportovenere.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/discover-portovenere-liguria-tuscany-700.png","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/discover-portovenere-liguria-tuscany-700.png","width":700,"height":92,"caption":"Discover Portovenere - Grand Hotel Portovenere"},"image":{"@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grandhotelportovenere","https:\/\/x.com\/ghportovenere","https:\/\/www.instagram.com\/ghportovenere\/","https:\/\/www.linkedin.com\/company\/grand-hotel-portovenere","https:\/\/www.youtube.com\/c\/Portoveneregrand"]},{"@type":"Person","@id":"https:\/\/discoverportovenere.com\/it\/#\/schema\/person\/77b4e306e5541ddeea527c99f7a03e89","name":"Portovenere","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","url":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","contentUrl":"https:\/\/discoverportovenere.com\/wp-content\/litespeed\/avatar\/c81798d116274486002a3e03fb94fc06.jpg?ver=1778500278","caption":"Portovenere"},"description":"5-star hotel in Portovenere, between the Bay of Poets and Cinque Terre in Liguria. Explore this beautiful Italian destination with Discover Portovenere Blog.","sameAs":["https:\/\/www.portoveneregrand.com\/","https:\/\/www.facebook.com\/pages\/Grand-Hotel-Portovenere\/158392434188761","https:\/\/www.instagram.com\/ghportovenere\/","https:\/\/x.com\/https:\/\/twitter.com\/ghportovenere"]}]}},"jetpack_featured_media_url":"https:\/\/discoverportovenere.com\/wp-content\/uploads\/2024\/06\/musical-history-la-spezia-gulf-of-poets.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p5GNh5-251","jetpack-related-posts":[{"id":7018,"url":"https:\/\/discoverportovenere.com\/it\/eventi-estate-portovenere-golfo-dei-poeti\/","url_meta":{"origin":7999,"position":0},"title":"Eventi estate 2025 a Portovenere e nel Golfo dei Poeti","author":"Portovenere","date":"14 Giugno 2025","format":false,"excerpt":"L\u2019estate \u00e8 un\u2019ottima stagione per visitare Portovenere e la provincia di La Spezia, soprattutto per chi cerca destinazioni pi\u00f9 tranquille sulla riviera ligure. Dai festival culturali alle avventure all\u2019aria aperta, durante l'estate c\u2019\u00e8 qualcosa per tutti i gusti! Scopri alcuni degli eventi pi\u00f9 emozionanti dell\u2019estate 2025 tra Portovenere e nel\u2026","rel":"","context":"In &quot;Eventi&quot;","block_context":{"text":"Eventi","link":"https:\/\/discoverportovenere.com\/it\/categoria\/eventi\/"},"img":{"alt_text":"summer events in portovenere lerici spezia (1)","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2023\/06\/summer-events-in-portovenere-lerici-spezia-1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6651,"url":"https:\/\/discoverportovenere.com\/it\/festival-jazz-spezia\/","url_meta":{"origin":7999,"position":1},"title":"Festival Internazionale del Jazz della Spezia 2025","author":"Portovenere","date":"31 Maggio 2025","format":false,"excerpt":"Il Festival Internazionale Del Jazz Della Spezia \u00e8 un evento musicale internazionale che si tiene nel suggestivo Golfo dei Poeti. Nel corso degli anni, \u00e8 stato ospitato dalle citt\u00e0 di La Spezia, Lerici e Portovenere. La manifestazione di musica jazz \u00e8 stata fondata nel 1969 da Tiberio Nicola, un musicista\u2026","rel":"","context":"In &quot;Eventi&quot;","block_context":{"text":"Eventi","link":"https:\/\/discoverportovenere.com\/it\/categoria\/eventi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/07\/la-spezia-jazz-festival-portovenere-2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/07\/la-spezia-jazz-festival-portovenere-2022.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/07\/la-spezia-jazz-festival-portovenere-2022.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/07\/la-spezia-jazz-festival-portovenere-2022.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2021\/07\/la-spezia-jazz-festival-portovenere-2022.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8571,"url":"https:\/\/discoverportovenere.com\/it\/antichi-porti-romani-golfo-poeti\/","url_meta":{"origin":7999,"position":2},"title":"Gli antichi porti romani nel Golfo dei Poeti","author":"Portovenere","date":"5 Maggio 2025","format":false,"excerpt":"Il Golfo dei Poeti \u00e8 un crocevia di storia. Qui, tra scogliere e baie tranquille, i Romani lasciarono segni tangibili del loro passaggio: ville marittime, attracchi, strutture portuali. Un mondo che riaffiora grazie a chi ancora oggi naviga sulle stesse rotte antiche\u2026 scopriamole! Il Golfo Della Spezia tra storia e\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"roman ports liguria - portovenere","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2025\/05\/roman-ports-liguria.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2025\/05\/roman-ports-liguria.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2025\/05\/roman-ports-liguria.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2025\/05\/roman-ports-liguria.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2025\/05\/roman-ports-liguria.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2025\/05\/roman-ports-liguria.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":6465,"url":"https:\/\/discoverportovenere.com\/it\/9-poeti-che-amarono-il-golfo-dei-poeti\/","url_meta":{"origin":7999,"position":3},"title":"9 poeti che amarono il Golfo dei Poeti","author":"Portovenere","date":"16 Novembre 2022","format":false,"excerpt":"Si chiamava Luna al tempo dell\u2019invasione romana, poi Porto lunense, Portus Veneris, Ericis portus, Gurfum Spezia e infine Golfo della Spezia. Ma da quando \u00e8 noto anche come Golfo dei Poeti? Dall\u2019estate del 1910, quando il drammaturgo fiorentino Sem Benelli, tenendo l\u2019orazione funebre alle esequie del suo amico scienziato e\u2026","rel":"","context":"In &quot;Arte&quot;","block_context":{"text":"Arte","link":"https:\/\/discoverportovenere.com\/it\/categoria\/arte\/"},"img":{"alt_text":"liguria poets writers golf of poets spezia","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2022\/11\/liguria-poets-writers-golf-of-poets-spezia.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":6554,"url":"https:\/\/discoverportovenere.com\/it\/primavera-golfo-dei-poeti\/","url_meta":{"origin":7999,"position":4},"title":"Primavera nel Golfo dei Poeti: cosa fare?","author":"Portovenere","date":"18 Febbraio 2023","format":false,"excerpt":"Stai riflettendo su dove andare per le tue prossime vacanze di primavera? Tra le sue innumerevoli attrazioni, la Liguria custodisce una destinazione da non perdere vicinissima alle Cinque Terre e alla Toscana. Il nome stesso di questa destinazione, Golfo dei Poeti, ti incuriosir\u00e0\u2026 Questo splendido golfo si estende tra i\u2026","rel":"","context":"In &quot;Idee di viaggio&quot;","block_context":{"text":"Idee di viaggio","link":"https:\/\/discoverportovenere.com\/it\/categoria\/idee-di-viaggio\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2018\/03\/Spring-Gulf-of-Poets.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":7778,"url":"https:\/\/discoverportovenere.com\/it\/giardini-golfo-poeti-spezia\/","url_meta":{"origin":7999,"position":5},"title":"I giardini pi\u00f9 belli del Golfo dei Poeti","author":"Portovenere","date":"24 Aprile 2024","format":false,"excerpt":"La Liguria \u00e8 famosa per i suoi meravigliosi giardini mediterranei. Tra i pi\u00f9 rinomati ci sono: I Giardini Hanbury a Ventimiglia, risalenti al 1867, grazie alla visione dell'esploratore inglese Thomas Hanbury; Il Giardino Pallanca a Bordighera, con pi\u00f9 di 3.200 diversi tipi di piante esotiche; Villa Nobel, dove visse per\u2026","rel":"","context":"In &quot;Arte&quot;","block_context":{"text":"Arte","link":"https:\/\/discoverportovenere.com\/it\/categoria\/arte\/"},"img":{"alt_text":"\u00a9 Dario Fusaro, Courtesy Cr\u00e9dit Agricole Italia","src":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/04\/villamarigola_phdariofusaro_courtesycreditagricole.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/04\/villamarigola_phdariofusaro_courtesycreditagricole.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/04\/villamarigola_phdariofusaro_courtesycreditagricole.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/04\/villamarigola_phdariofusaro_courtesycreditagricole.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/discoverportovenere.com\/wp-content\/uploads\/2024\/04\/villamarigola_phdariofusaro_courtesycreditagricole.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts\/7999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/comments?post=7999"}],"version-history":[{"count":0,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/posts\/7999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/media\/7991"}],"wp:attachment":[{"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/media?parent=7999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/categories?post=7999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/discoverportovenere.com\/it\/wp-json\/wp\/v2\/tags?post=7999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}